{"id":9473,"date":"2022-03-24T08:08:57","date_gmt":"2022-03-24T14:08:57","guid":{"rendered":"https:\/\/soclose.mx\/blog\/?p=9473"},"modified":"2022-03-23T23:21:57","modified_gmt":"2022-03-24T05:21:57","slug":"que-es-y-cuando-se-celebra-el-viernes-de-samaritana-en-oaxaca","status":"publish","type":"post","link":"https:\/\/soclose.mx\/blog\/ay-goeeee\/que-es-y-cuando-se-celebra-el-viernes-de-samaritana-en-oaxaca\/","title":{"rendered":"\u00bfQu\u00e9 es y cu\u00e1ndo se celebra el Viernes de Samaritana en Oaxaca?"},"content":{"rendered":"<p><strong>M\u00e9xico\u00a0<\/strong>est\u00e1 lleno de costumbres y\u00a0<strong>tradiciones<\/strong> y cuando hablamos de\u00a0<a href=\"https:\/\/soclose.mx\/blog\/?s=oaxaca\" target=\"_blank\" rel=\"noopener\"><strong>Oaxaca<\/strong><\/a>,\u00a0no es la excepci\u00f3n;\u00a0en el estado existen algunas\u00a0<strong>fechas<\/strong> bastante especiales, como el <strong>Viernes de Samaritana.<\/strong><\/p>\n<p>Esta celebraci\u00f3n se basa en un pasaje muy famoso del <strong>Evangelio de San Juan<\/strong>,\u00a0 el encuentro entre <strong>Jes\u00fas\u00a0<\/strong>con una mujer que,\u00a0al verlo, le ofreci\u00f3\u00a0<strong>agua<\/strong>, justo junto al pozo de <strong>Jacob;<\/strong>\u00a0por este evento las\u00a0mujeres oaxaque\u00f1as conmemoran la fecha saliendo al portal de sus casas, para regalar <strong>aguas frescas<\/strong> a quien lo necesite y pase por ah\u00ed.<\/p>\n<p>La tradici\u00f3n ascendi\u00f3 desde el terreno religioso hasta convertirse en un evento cultural\u00a0festejado en\u00a0<strong>Oaxaca\u00a0<\/strong>de m\u00faltiples formas, este se festeja cada cuarto viernes de\u00a0<strong>Cuaresma<\/strong>, o tres semanas antes del\u00a0<strong>Viernes Santo<\/strong>, este a\u00f1o se llevar\u00e1 a cabo el <strong>25 de marzo<\/strong>.<\/p>\n<p>Adem\u00e1s de las bebidas, tambi\u00e9n se regalan otros alimentos t\u00edpicos como las\u00a0nieves\u00a0y durante la celebraci\u00f3n las mujeres que participan suelen portar\u00a0los\u00a0trajes t\u00edpicos de la regi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico\u00a0est\u00e1 lleno de costumbres y\u00a0tradiciones y cuando hablamos de\u00a0Oaxaca,\u00a0no es la excepci\u00f3n;\u00a0en el estado existen algunas\u00a0fechas bastante especiales, como el Viernes de Samaritana. Esta celebraci\u00f3n se basa en un pasaje muy famoso del Evangelio de San Juan,\u00a0 el encuentro entre Jes\u00fas\u00a0con una mujer que,\u00a0al verlo, le ofreci\u00f3\u00a0agua, justo junto al pozo de Jacob;\u00a0por este evento las\u00a0mujeres oaxaque\u00f1as conmemoran la fecha saliendo al portal de sus casas, para regalar aguas frescas a quien lo necesite y pase por ah\u00ed. La tradici\u00f3n ascendi\u00f3 desde el terreno religioso hasta convertirse en un evento cultural\u00a0festejado en\u00a0Oaxaca\u00a0de m\u00faltiples formas, este se festeja cada cuarto viernes<\/p>\n","protected":false},"author":8,"featured_media":9474,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[194,1885],"class_list":["post-9473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ay-goeeee","tag-oaxaca","tag-viernes-de-samaritana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 es y cu\u00e1ndo se celebra el Viernes de Samaritana en Oaxaca? - So Close<\/title>\n<meta name=\"description\" content=\"Esta celebraci\u00f3n naci\u00f3 como una costumbre religiosa y lentamente fue convirti\u00e9ndose en un evento cultural oaxaque\u00f1o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es y cu\u00e1ndo se celebra el Viernes de Samaritana en Oaxaca? - So Close\" \/>\n<meta property=\"og:description\" content=\"Esta celebraci\u00f3n naci\u00f3 como una costumbre religiosa y lentamente fue convirti\u00e9ndose en un evento cultural oaxaque\u00f1o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/\" \/>\n<meta property=\"og:site_name\" content=\"So Close\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/mikexever\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-24T14:08:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2022\/03\/Copia-de-Principal-So-Close-blog-1-17.png?fit=1240%2C700&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Miguel Angel Romero\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Mikerecomienda\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Miguel Angel Romero\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/\"},\"author\":{\"name\":\"Miguel Angel Romero\",\"@id\":\"https:\/\/soclose.mx\/blog\/#\/schema\/person\/cddec6ccd5d7037d286395fb411e23f1\"},\"headline\":\"\u00bfQu\u00e9 es y cu\u00e1ndo se celebra el Viernes de Samaritana en Oaxaca?\",\"datePublished\":\"2022-03-24T14:08:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/\"},\"wordCount\":188,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/soclose.mx\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2022\/03\/Copia-de-Principal-So-Close-blog-1-17.png?fit=1240%2C700&ssl=1\",\"keywords\":[\"oaxaca\",\"Viernes de Samaritana\"],\"articleSection\":[\"\u00a1Ay goeeee!\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/\",\"url\":\"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/\",\"name\":\"\u00bfQu\u00e9 es y cu\u00e1ndo se celebra el Viernes de Samaritana en Oaxaca? - So Close\",\"isPartOf\":{\"@id\":\"https:\/\/soclose.mx\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2022\/03\/Copia-de-Principal-So-Close-blog-1-17.png?fit=1240%2C700&ssl=1\",\"datePublished\":\"2022-03-24T14:08:57+00:00\",\"description\":\"Esta celebraci\u00f3n naci\u00f3 como una costumbre religiosa y lentamente fue convirti\u00e9ndose en un evento cultural oaxaque\u00f1o.\",\"breadcrumb\":{\"@id\":\"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2022\/03\/Copia-de-Principal-So-Close-blog-1-17.png?fit=1240%2C700&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2022\/03\/Copia-de-Principal-So-Close-blog-1-17.png?fit=1240%2C700&ssl=1\",\"width\":1240,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/soclose.mx\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 es y cu\u00e1ndo se celebra el Viernes de Samaritana en Oaxaca?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/soclose.mx\/blog\/#website\",\"url\":\"https:\/\/soclose.mx\/blog\/\",\"name\":\"So Close\",\"description\":\"Hacemos contenidos de M\u00e9xico\",\"publisher\":{\"@id\":\"https:\/\/soclose.mx\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/soclose.mx\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/soclose.mx\/blog\/#organization\",\"name\":\"So Close\",\"url\":\"https:\/\/soclose.mx\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/soclose.mx\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2020\/12\/LOGO_SOCLOSE_COLOR-e1608310133507.png?fit=2858%2C1264&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2020\/12\/LOGO_SOCLOSE_COLOR-e1608310133507.png?fit=2858%2C1264&ssl=1\",\"width\":2858,\"height\":1264,\"caption\":\"So Close\"},\"image\":{\"@id\":\"https:\/\/soclose.mx\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/soclose.mx\/blog\/#\/schema\/person\/cddec6ccd5d7037d286395fb411e23f1\",\"name\":\"Miguel Angel Romero\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/soclose.mx\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/45b44006b4f93497bb24d251f77bc39385015bfa120582412df580dbfcbb14f3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/45b44006b4f93497bb24d251f77bc39385015bfa120582412df580dbfcbb14f3?s=96&d=mm&r=g\",\"caption\":\"Miguel Angel Romero\"},\"sameAs\":[\"http:\/\/\/mikexever.blogspot.com\/\",\"www.facebook.com\/mikexever\/\",\"https:\/\/x.com\/Mikerecomienda\"],\"url\":\"https:\/\/soclose.mx\/blog\/author\/mike\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es y cu\u00e1ndo se celebra el Viernes de Samaritana en Oaxaca? - So Close","description":"Esta celebraci\u00f3n naci\u00f3 como una costumbre religiosa y lentamente fue convirti\u00e9ndose en un evento cultural oaxaque\u00f1o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/","og_locale":"es_MX","og_type":"article","og_title":"\u00bfQu\u00e9 es y cu\u00e1ndo se celebra el Viernes de Samaritana en Oaxaca? - So Close","og_description":"Esta celebraci\u00f3n naci\u00f3 como una costumbre religiosa y lentamente fue convirti\u00e9ndose en un evento cultural oaxaque\u00f1o.","og_url":"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/","og_site_name":"So Close","article_author":"www.facebook.com\/mikexever\/","article_published_time":"2022-03-24T14:08:57+00:00","og_image":[{"width":1240,"height":700,"url":"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2022\/03\/Copia-de-Principal-So-Close-blog-1-17.png?fit=1240%2C700&ssl=1","type":"image\/png"}],"author":"Miguel Angel Romero","twitter_card":"summary_large_image","twitter_creator":"@Mikerecomienda","twitter_misc":{"Escrito por":"Miguel Angel Romero","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/#article","isPartOf":{"@id":"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/"},"author":{"name":"Miguel Angel Romero","@id":"https:\/\/soclose.mx\/blog\/#\/schema\/person\/cddec6ccd5d7037d286395fb411e23f1"},"headline":"\u00bfQu\u00e9 es y cu\u00e1ndo se celebra el Viernes de Samaritana en Oaxaca?","datePublished":"2022-03-24T14:08:57+00:00","mainEntityOfPage":{"@id":"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/"},"wordCount":188,"commentCount":0,"publisher":{"@id":"https:\/\/soclose.mx\/blog\/#organization"},"image":{"@id":"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2022\/03\/Copia-de-Principal-So-Close-blog-1-17.png?fit=1240%2C700&ssl=1","keywords":["oaxaca","Viernes de Samaritana"],"articleSection":["\u00a1Ay goeeee!"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/","url":"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/","name":"\u00bfQu\u00e9 es y cu\u00e1ndo se celebra el Viernes de Samaritana en Oaxaca? - So Close","isPartOf":{"@id":"https:\/\/soclose.mx\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/#primaryimage"},"image":{"@id":"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2022\/03\/Copia-de-Principal-So-Close-blog-1-17.png?fit=1240%2C700&ssl=1","datePublished":"2022-03-24T14:08:57+00:00","description":"Esta celebraci\u00f3n naci\u00f3 como una costumbre religiosa y lentamente fue convirti\u00e9ndose en un evento cultural oaxaque\u00f1o.","breadcrumb":{"@id":"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/#primaryimage","url":"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2022\/03\/Copia-de-Principal-So-Close-blog-1-17.png?fit=1240%2C700&ssl=1","contentUrl":"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2022\/03\/Copia-de-Principal-So-Close-blog-1-17.png?fit=1240%2C700&ssl=1","width":1240,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/soclose.mx\/blog\/tag\/juan-rulfo-frases-mujeres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/soclose.mx\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 es y cu\u00e1ndo se celebra el Viernes de Samaritana en Oaxaca?"}]},{"@type":"WebSite","@id":"https:\/\/soclose.mx\/blog\/#website","url":"https:\/\/soclose.mx\/blog\/","name":"So Close","description":"Hacemos contenidos de M\u00e9xico","publisher":{"@id":"https:\/\/soclose.mx\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soclose.mx\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/soclose.mx\/blog\/#organization","name":"So Close","url":"https:\/\/soclose.mx\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/soclose.mx\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2020\/12\/LOGO_SOCLOSE_COLOR-e1608310133507.png?fit=2858%2C1264&ssl=1","contentUrl":"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2020\/12\/LOGO_SOCLOSE_COLOR-e1608310133507.png?fit=2858%2C1264&ssl=1","width":2858,"height":1264,"caption":"So Close"},"image":{"@id":"https:\/\/soclose.mx\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/soclose.mx\/blog\/#\/schema\/person\/cddec6ccd5d7037d286395fb411e23f1","name":"Miguel Angel Romero","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/soclose.mx\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/45b44006b4f93497bb24d251f77bc39385015bfa120582412df580dbfcbb14f3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/45b44006b4f93497bb24d251f77bc39385015bfa120582412df580dbfcbb14f3?s=96&d=mm&r=g","caption":"Miguel Angel Romero"},"sameAs":["http:\/\/\/mikexever.blogspot.com\/","www.facebook.com\/mikexever\/","https:\/\/x.com\/Mikerecomienda"],"url":"https:\/\/soclose.mx\/blog\/author\/mike\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2022\/03\/Copia-de-Principal-So-Close-blog-1-17.png?fit=1240%2C700&ssl=1","jetpack-related-posts":[{"id":5580,"url":"https:\/\/soclose.mx\/blog\/lugares\/los-5-pueblos-magicos-de-oaxaca-que-debes-tener-en-tu-lista-de-viaje\/","url_meta":{"origin":9473,"position":0},"title":"Los 5 pueblos m\u00e1gicos de Oaxaca que debes tener en tu lista de viaje","author":"So Close","date":"4 enero, 2021","format":false,"excerpt":"Oaxaca es uno de los estados m\u00e1s ricos en cultura y tradiciones de todo M\u00e9xico, por ello es que si en tus planes est\u00e1 alg\u00fan d\u00eda visitarlo, esta lista de sus cinco pueblos m\u00e1gicos te ayudar\u00e1 mucho para no perder tiempo y llegar directo a lo que m\u00e1s te interese.\u2026","rel":"","context":"En &quot;Lugares&quot;","block_context":{"text":"Lugares","link":"https:\/\/soclose.mx\/blog\/category\/lugares\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/01\/Principal-So-Close-blog-1.jpg?fit=1200%2C677&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/01\/Principal-So-Close-blog-1.jpg?fit=1200%2C677&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/01\/Principal-So-Close-blog-1.jpg?fit=1200%2C677&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/01\/Principal-So-Close-blog-1.jpg?fit=1200%2C677&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/01\/Principal-So-Close-blog-1.jpg?fit=1200%2C677&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":9609,"url":"https:\/\/soclose.mx\/blog\/news-feed\/a-festejar-los-90-anos-de-la-guelaguetza\/","url_meta":{"origin":9473,"position":1},"title":"\u00a1A festejar los 90 a\u00f1os de la Guelaguetza!","author":"Miguel Angel Romero","date":"19 abril, 2022","format":false,"excerpt":"La Guelaguetza regresa a\u00a0Oaxaca\u00a0de manera presencial luego de dos a\u00f1os de ausencia debido a la pandemia por Covid-19 y ser\u00e1 la Rotonda de las Azucenas, la que ser\u00e1 testigo nuevamente de la fiesta m\u00e1s grande del estado. Los d\u00edas 8, 9, 15 y 16 de julio \u00a0tendr\u00e1n lugar los esperados\u00a0Convites\u2026","rel":"","context":"En &quot;News feed&quot;","block_context":{"text":"News feed","link":"https:\/\/soclose.mx\/blog\/category\/news-feed\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2022\/04\/Copia-de-Principal-So-Close-blog-3.png?fit=1200%2C677&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2022\/04\/Copia-de-Principal-So-Close-blog-3.png?fit=1200%2C677&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2022\/04\/Copia-de-Principal-So-Close-blog-3.png?fit=1200%2C677&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2022\/04\/Copia-de-Principal-So-Close-blog-3.png?fit=1200%2C677&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2022\/04\/Copia-de-Principal-So-Close-blog-3.png?fit=1200%2C677&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":7466,"url":"https:\/\/soclose.mx\/blog\/news-feed\/oaxaca-es-nominada-en-el-world-travel-awards-otra-vez\/","url_meta":{"origin":9473,"position":2},"title":"Oaxaca es nominada en el World Travel Awards (otra vez)","author":"Miguel Angel Romero","date":"12 octubre, 2021","format":false,"excerpt":"Oaxaca sigue dando de qu\u00e9 hablar y no es para menos, ya que su riqueza gastron\u00f3mica, tradiciones y costumbres adem\u00e1s de la calidad de los servicios tur\u00edsticos, hicieron que fuera nominada (de nueva cuenta) en el World Travel Awards 2021. As\u00ed es, aquella regi\u00f3n que posee todas las grandezas de\u2026","rel":"","context":"En &quot;News feed&quot;","block_context":{"text":"News feed","link":"https:\/\/soclose.mx\/blog\/category\/news-feed\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/10\/Copia-de-Principal-So-Close-blog-5-1.png?fit=1200%2C677&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/10\/Copia-de-Principal-So-Close-blog-5-1.png?fit=1200%2C677&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/10\/Copia-de-Principal-So-Close-blog-5-1.png?fit=1200%2C677&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/10\/Copia-de-Principal-So-Close-blog-5-1.png?fit=1200%2C677&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/10\/Copia-de-Principal-So-Close-blog-5-1.png?fit=1200%2C677&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":7789,"url":"https:\/\/soclose.mx\/blog\/ay-goeeee\/elotes-gigantes-solo-en-oaxaca\/","url_meta":{"origin":9473,"position":3},"title":"\u00a1Elotes gigantes!&#8230; s\u00f3lo en Oaxaca","author":"Miguel Angel Romero","date":"9 noviembre, 2021","format":false,"excerpt":"Imag\u00ednate un elote calientito, muy tierno preparado con mayonesa, queso y chile piqu\u00edn, seguro ya se te hizo agua la boca, ahora, imag\u00ednatelo que fuera gigante, \u00bfte lo acabar\u00edas? La gastronom\u00eda de\u00a0Oaxaca\u00a0es uno de los motivos que mueven a millones de turistas a esa entidad, pero en los \u00faltimos d\u00edas\u2026","rel":"","context":"En &quot;\u00a1Ay goeeee!&quot;","block_context":{"text":"\u00a1Ay goeeee!","link":"https:\/\/soclose.mx\/blog\/category\/ay-goeeee\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/11\/Copia-de-Principal-So-Close-blog-4-3.png?fit=1200%2C677&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/11\/Copia-de-Principal-So-Close-blog-4-3.png?fit=1200%2C677&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/11\/Copia-de-Principal-So-Close-blog-4-3.png?fit=1200%2C677&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/11\/Copia-de-Principal-So-Close-blog-4-3.png?fit=1200%2C677&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/11\/Copia-de-Principal-So-Close-blog-4-3.png?fit=1200%2C677&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":7240,"url":"https:\/\/soclose.mx\/blog\/comida-mexicana\/las-quince-letras-es-el-mejor-restaurante-autentico-y-artesanal-y-es-mexicano\/","url_meta":{"origin":9473,"position":4},"title":"Francia reconoce al restaurante oaxaque\u00f1o, Las Quince Letras","author":"Miguel Angel Romero","date":"14 septiembre, 2021","format":false,"excerpt":"Las Quince Letras, con casi 30 a\u00f1os de vida, fue\u00a0reconocido como el Mejor Restaurante Aut\u00e9ntico y Artesanal en el Mundo 2021, por\u00a0La Liste en Francia. \u00a0 Ver esta publicaci\u00f3n en Instagram \u00a0 Una publicaci\u00f3n compartida por Las Quince Letras (@lasquinceletrasoax) Desde\u00a01992, Celia Flori\u00e1n,\u00a0abri\u00f3 este\u00a0espacio culinario\u00a0junto a\u00a0Fidel M\u00e9ndez, para transmitir a\u2026","rel":"","context":"En &quot;Comida mexicana&quot;","block_context":{"text":"Comida mexicana","link":"https:\/\/soclose.mx\/blog\/category\/comida-mexicana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/09\/Principal-So-Close-blog-15-1.jpg?fit=1200%2C677&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/09\/Principal-So-Close-blog-15-1.jpg?fit=1200%2C677&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/09\/Principal-So-Close-blog-15-1.jpg?fit=1200%2C677&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/09\/Principal-So-Close-blog-15-1.jpg?fit=1200%2C677&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/09\/Principal-So-Close-blog-15-1.jpg?fit=1200%2C677&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":7513,"url":"https:\/\/soclose.mx\/blog\/lugares\/lo-que-debes-saber-de-hierve-el-agua\/","url_meta":{"origin":9473,"position":5},"title":"Lo que debes saber de Hierve el Agua","author":"Miguel Angel Romero","date":"22 octubre, 2021","format":false,"excerpt":"Uno de los estados que m\u00e1s ha brillado por todas sus cualidades es Oaxaca y \u00e9ste a su vez posee uno de las zonas m\u00e1s bellas que existen: Hierve el Agua. El sitio que se localiza junto al poblado Roegu\u00eda, a 5 km de San Lorenzo Albarradas que, a su\u2026","rel":"","context":"En &quot;Lugares&quot;","block_context":{"text":"Lugares","link":"https:\/\/soclose.mx\/blog\/category\/lugares\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/10\/Copia-de-Principal-So-Close-blog-13.png?fit=1200%2C677&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/10\/Copia-de-Principal-So-Close-blog-13.png?fit=1200%2C677&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/10\/Copia-de-Principal-So-Close-blog-13.png?fit=1200%2C677&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/10\/Copia-de-Principal-So-Close-blog-13.png?fit=1200%2C677&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/soclose.mx\/blog\/wp-content\/uploads\/2021\/10\/Copia-de-Principal-So-Close-blog-13.png?fit=1200%2C677&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/soclose.mx\/blog\/wp-json\/wp\/v2\/posts\/9473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soclose.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soclose.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soclose.mx\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/soclose.mx\/blog\/wp-json\/wp\/v2\/comments?post=9473"}],"version-history":[{"count":0,"href":"https:\/\/soclose.mx\/blog\/wp-json\/wp\/v2\/posts\/9473\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soclose.mx\/blog\/wp-json\/wp\/v2\/media\/9474"}],"wp:attachment":[{"href":"https:\/\/soclose.mx\/blog\/wp-json\/wp\/v2\/media?parent=9473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soclose.mx\/blog\/wp-json\/wp\/v2\/categories?post=9473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soclose.mx\/blog\/wp-json\/wp\/v2\/tags?post=9473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}